{"id":5762,"date":"2017-07-27T09:40:09","date_gmt":"2017-07-27T12:40:09","guid":{"rendered":"http:\/\/www.esportesbrasilia.com.br\/noticias\/?p=5762"},"modified":"2017-07-27T09:40:09","modified_gmt":"2017-07-27T12:40:09","slug":"bruno-savignani-demonstra-desejo-de-permanencia-no-comando-da-equipe-de-basquete-do-df","status":"publish","type":"post","link":"https:\/\/www.esportesbrasilia.com.br\/noticias\/basquete\/bruno-savignani-demonstra-desejo-de-permanencia-no-comando-da-equipe-de-basquete-do-df.html","title":{"rendered":"Bruno Savignani demonstra desejo de perman\u00eancia no comando da equipe de basquete do DF"},"content":{"rendered":"<p>A inter-temporada do Novo Basquete Brasil (NBB) n\u00e3o est\u00e1 sendo das melhores para a equipe de basquete de Bras\u00edlia. Al\u00e9m de perder os patroc\u00ednios de Terracap e UniCEUB nos \u00faltimos meses, o time da capital federal teve de lidar com a sa\u00edda de dois pilares do clube: Guilherme Giovannoni e F\u00falvio, que defender\u00e3o o Vasco a partir do pr\u00f3ximo calend\u00e1rio de disputas do basquete nacional.<\/p>\n<p>Contudo, mesmo nessa mar\u00e9 negativa, algumas not\u00edcias podem tranquilizar o torcedor do time candango. Bruno Savignani, atual treinador da equipe do DF, manifestou interesse em continuar no comando do clube. Em entrevista exclusiva \u00e0 <strong>Esportes Bras\u00edlia<\/strong>, Bruno informou que \u201cainda \u00e9 preciso confirmar, mas a minha vontade \u00e9 que sim. Est\u00e3o ainda resolvendo quest\u00f5es de patroc\u00ednios. Depois vamos conversar e nos acertar\u201d.<\/p>\n<p>Apesar de a perman\u00eancia do treinador ainda n\u00e3o estar acertada, Bruno afirma que a diretoria est\u00e1 trabalhando duro para isso. Por enquanto, ele mostra confian\u00e7a. \u201cEspero que d\u00ea tudo certo. Sou sempre positivo\u201d, afirmou.<\/p>\n<div id=\"attachment_3541\" style=\"width: 2058px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3541\" class=\"size-full wp-image-3541\" src=\"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-content\/uploads\/brunosavignani_britojr.jpg\" alt=\"T\u00e9cnico Bruno Savignani afirma que est\u00e1 em negocia\u00e7\u00e3o para permanecer na pr\u00f3xima temporada do NBB - Foto: Brito Junior\" width=\"2048\" height=\"1363\" srcset=\"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-content\/uploads\/brunosavignani_britojr.jpg 2048w, https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-content\/uploads\/brunosavignani_britojr-300x200.jpg 300w, https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-content\/uploads\/brunosavignani_britojr-768x511.jpg 768w, https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-content\/uploads\/brunosavignani_britojr-1024x682.jpg 1024w, https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-content\/uploads\/brunosavignani_britojr-696x463.jpg 696w, https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-content\/uploads\/brunosavignani_britojr-1068x711.jpg 1068w, https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-content\/uploads\/brunosavignani_britojr-631x420.jpg 631w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><p id=\"caption-attachment-3541\" class=\"wp-caption-text\">T\u00e9cnico Bruno Savignani afirma que est\u00e1 em negocia\u00e7\u00e3o para permanecer na pr\u00f3xima temporada do NBB &#8211; Foto: Brito Junior<\/p><\/div>\n<p>Bruno lamentou as transfer\u00eancias de Giovannoni e F\u00falvio para o Rio de Janeiro. \u201c\u00c9 sempre ruim perder dois grandes jogadores como eles. Com muitas qualidades, experi\u00eancias e hist\u00f3rias em Bras\u00edlia, principalmente o Guilherme. Mas estas perdas fazem parte do esporte\u201d, ressalta.<\/p>\n<p>De qualquer forma, o comandante tem a expectativa de uma equipe competitiva para a pr\u00f3xima temporada. Como j\u00e1 noticiado pela <strong>Esportes Bras\u00edlia<\/strong>, apenas quatro atletas t\u00eam contrato assegurado com o time de basquete da capital: Lucas Mariano, Deryk, Jo\u00e3o Phylippe e Jeferson Campos. Com esses jogadores \u00e0 disposi\u00e7\u00e3o, Bruno acredita que Bras\u00edlia tem uma boa base. Quanto aos outros atletas, o treinador comunicou que eles est\u00e3o negociando os v\u00ednculos com o clube do DF.<\/p>\n<p>Bruno Savignani \u00e9 t\u00e9cnico do time de basquete de Bras\u00edlia desde 2015, e levou o clube \u00e0s semifinais do NBB em 2015\/2016 e \u00e0s quartas de final em 2016\/2017. Tamb\u00e9m comandou a equipe na Liga Sul-Americana de Basquete de 2016, quando foi eliminado do torneio na segunda fase.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A inter-temporada do Novo Basquete Brasil (NBB) n\u00e3o est\u00e1 sendo das melhores para a equipe de basquete de Bras\u00edlia. Al\u00e9m de perder os patroc\u00ednios de Terracap e UniCEUB nos \u00faltimos meses, o time da capital federal teve de lidar com a sa\u00edda de dois pilares do clube: Guilherme Giovannoni e F\u00falvio, que defender\u00e3o o Vasco [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":3541,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-5762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquete"],"_links":{"self":[{"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=5762"}],"version-history":[{"count":1,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5762\/revisions"}],"predecessor-version":[{"id":5763,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5762\/revisions\/5763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/media\/3541"}],"wp:attachment":[{"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=5762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=5762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=5762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}