{"id":22980,"date":"2022-12-30T17:28:38","date_gmt":"2022-12-30T20:28:38","guid":{"rendered":"https:\/\/www.esportesbrasilia.com.br\/noticias\/?p=22980"},"modified":"2022-12-30T17:28:39","modified_gmt":"2022-12-30T20:28:39","slug":"apos-uma-temporada-e-meia-ricardo-fischer-deixa-o-brasilia-basquete","status":"publish","type":"post","link":"https:\/\/www.esportesbrasilia.com.br\/noticias\/basquete\/apos-uma-temporada-e-meia-ricardo-fischer-deixa-o-brasilia-basquete.html","title":{"rendered":"Ap\u00f3s uma temporada e meia, Ricardo Fischer deixa o Bras\u00edlia Basquete"},"content":{"rendered":"\n<p><strong>Foto: Matheus Maranh\u00e3o\/Bras\u00edlia Basquete<\/strong><\/p>\n\n\n\n<p>35 partidas, 472 pontos e 164 assist\u00eancias. Ap\u00f3s uma temporada e quase metade da segunda vestindo a camisa do Bras\u00edlia Basquete, o armador Ricardo Fischer anunciou, nas redes sociais, que deixou o time nesta sexta-feira (30).<\/p>\n\n\n\n<p>Em uma postagem no Instagram, Ricardo comentou sobre a sa\u00edda dele do time alien\u00edgena: &#8220;Dentro de quadra tivemos desafios que precisaram ser superados durante uma primeira temporada muito dif\u00edcil e fora de quadra tamb\u00e9m precisamos encontrar solu\u00e7\u00f5es para outros desafios&#8221;, disse.<\/p>\n\n\n\n<p>&#8220;Tivemos obst\u00e1culos, crescemos para passar por eles, fizemos grandes partidas e sentimos de verdade o que \u00e9 defender esse gigante do basquete nacional&#8221;, completou o armador.<\/p>\n\n\n\n<p>Ricardo deixa o Bras\u00edlia Basquete em meio \u00e0s den\u00fancias, divulgadas primeiro pelo <em>GloboEsporte.com<\/em> e confirmadas pela reportagem da <strong>Esportes Bras\u00edlia<\/strong>, de que o sal\u00e1rio do time esteja em atraso.<\/p>\n\n\n\n<p>Em uma outra postagem, em outra rede social, no \u00faltimo dia 13 de dezembro, o atleta reclamou dos dois meses que estaria sem receber o pagamento. &#8220;S\u00f3 queremos o que \u00e9 nosso por direito&#8221;, disse Fischer.<\/p>\n\n\n\n<p>Dois dias depois, ele comentou o assunto durante a transmiss\u00e3o da <strong>EB<\/strong> do confronto contra o Paulistano: &#8220;A gente decidiu jogar. Se a gente decidiu isso, temos que dar o nosso melhor. N\u00e3o podemos usar o que t\u00e1 acontecendo como lema&#8221;, ressaltou.<\/p>\n\n\n\n<p>Durante a temporada 2022 do NBB, Ricardo Fischer vinha atuando, em m\u00e9dia, durante quase 32 minutos em quadra. Na m\u00e9dia da temporada, foram 14 pontos por jogo, cinco rebotes e cinco assist\u00eancias, com 15 de efici\u00eancia.<\/p>\n\n\n\n<p>Sem Ricardo Fischer, o Bras\u00edlia Basquete j\u00e1 volta \u00e0s quadras nesta ter\u00e7a-feira (03.01). A equipe recebe o Pato Basquete \u00e0s 19h30, no Gin\u00e1sio Nilson Nelson.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Matheus Maranh\u00e3o\/Bras\u00edlia Basquete 35 partidas, 472 pontos e 164 assist\u00eancias. Ap\u00f3s uma temporada e quase metade da segunda vestindo a camisa do Bras\u00edlia Basquete, o armador Ricardo Fischer anunciou, nas redes sociais, que deixou o time nesta sexta-feira (30). Em uma postagem no Instagram, Ricardo comentou sobre a sa\u00edda dele do time alien\u00edgena: &#8220;Dentro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[886,1095],"class_list":["post-22980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquete","tag-brasilia-basquete","tag-ricardo-fischer"],"_links":{"self":[{"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/posts\/22980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=22980"}],"version-history":[{"count":1,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/posts\/22980\/revisions"}],"predecessor-version":[{"id":22981,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/posts\/22980\/revisions\/22981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/media\/20778"}],"wp:attachment":[{"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=22980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=22980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esportesbrasilia.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=22980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}